{"id":4242,"date":"2019-12-20T21:53:59","date_gmt":"2019-12-20T21:53:59","guid":{"rendered":"https:\/\/arheo.cesis.lv\/db\/cm-13545-1-11\/"},"modified":"2022-08-04T19:31:44","modified_gmt":"2022-08-04T19:31:44","slug":"cm-13545-1-11","status":"publish","type":"items","link":"https:\/\/arheo.cesis.lv\/en\/db\/cm-13545-1-11\/","title":{"rendered":"Clothing decorations"},"content":{"rendered":"","protected":false},"featured_media":2833,"parent":0,"template":"","materials":[47,46],"types":[257],"locations":[38],"time_periods":[64],"_links":{"self":[{"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/items\/4242"}],"collection":[{"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/items"}],"about":[{"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/types\/items"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/media\/2833"}],"wp:attachment":[{"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/media?parent=4242"}],"wp:term":[{"taxonomy":"materials","embeddable":true,"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/materials?post=4242"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/types?post=4242"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/locations?post=4242"},{"taxonomy":"time_periods","embeddable":true,"href":"https:\/\/arheo.cesis.lv\/en\/wp-json\/wp\/v2\/time_periods?post=4242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}